{"id":98083,"date":"2025-10-17T10:03:21","date_gmt":"2025-10-17T14:03:21","guid":{"rendered":"https:\/\/www.muralunique.com\/?post_type=product&#038;p=98083"},"modified":"2025-10-17T12:01:53","modified_gmt":"2025-10-17T16:01:53","slug":"art-fluide-luxueux","status":"publish","type":"product","link":"https:\/\/www.muralunique.com\/fr\/produit\/art-fluide-luxueux\/","title":{"rendered":"Art fluide luxueux"},"content":{"rendered":"<p>Peinture abstraite de luxe r\u00e9alis\u00e9e \u00e0 l&#8217;aide de la technique de l&#8217;encre \u00e0 alcool, m\u00e9langeant des peintures noires, grises et dor\u00e9es. Imitation de marbre sculpt\u00e9 avec des veines dor\u00e9es lumineuses. Design doux et cr\u00e9meux  en bronze &#038; dor\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peinture abstraite de luxe r\u00e9alis\u00e9e \u00e0 l&#8217;aide de la technique de l&#8217;encre \u00e0 alcool, m\u00e9langeant des peintures noires, grises et dor\u00e9es. Imitation de marbre sculpt\u00e9 avec des veines dor\u00e9es lumineuses. Design doux et cr\u00e9meux en bronze &#038; dor\u00e9.<\/p>\n","protected":false},"featured_media":98160,"template":"","meta":{"_acf_changed":false},"product_brand":[203],"product_cat":[10569,401],"product_tag":[8654],"class_list":["post-98083","product","type-product","status-publish","has-post-thumbnail","artist-artistes-varies","product_brand-muralunique-com","product_cat-ecolux","product_cat-tous-nos-produits","product_tag-murale-perso","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.muralunique.com\/fr\/wp-json\/wp\/v2\/product\/98083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muralunique.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.muralunique.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muralunique.com\/fr\/wp-json\/wp\/v2\/media\/98160"}],"wp:attachment":[{"href":"https:\/\/www.muralunique.com\/fr\/wp-json\/wp\/v2\/media?parent=98083"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.muralunique.com\/fr\/wp-json\/wp\/v2\/product_brand?post=98083"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.muralunique.com\/fr\/wp-json\/wp\/v2\/product_cat?post=98083"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.muralunique.com\/fr\/wp-json\/wp\/v2\/product_tag?post=98083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}